{"id":6653,"date":"2017-11-03T23:56:50","date_gmt":"2017-11-03T22:56:50","guid":{"rendered":"http:\/\/www.lamanchette.be\/main\/?p=6653"},"modified":"2017-11-06T12:03:09","modified_gmt":"2017-11-06T11:03:09","slug":"saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires","status":"publish","type":"post","link":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/","title":{"rendered":"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires !"},"content":{"rendered":"<p>Il est un fait certain que l\u2019ann\u00e9e 2017 a \u00e9t\u00e9 l\u2019ann\u00e9e butoir de toutes les d\u00e9couvertes ind\u00e9centes des magouilles financi\u00e8res des partis politiques.<\/p>\n<p>De mani\u00e8re g\u00e9n\u00e9rale, le contribuable a \u00e9t\u00e9 ballot\u00e9 de scandale en scandale putrides qui ont \u00e9videmment donn\u00e9 un coup dans la confiance des \u00e9lecteurs potentiels.<\/p>\n<p>D\u2019ailleurs, le PS a m\u00eame d\u00fb accuser divers barom\u00e8tres politiques tr\u00e8s n\u00e9gatifs qui l\u2019ont d\u00e9boulonn\u00e9, de mani\u00e8re nationale, \u00e0 des places m\u00e9connues par le parti jusqu\u2019\u00e0 pr\u00e9sent.<\/p>\n<p>Toujours dans ce contexte assez calamiteux, des fouilles dans les budgets communaux bruxellois de 2016 m\u2019ont permis de dresser un petit tableau comparatif de certaines d\u00e9penses locales.<\/p>\n<p>Le bilan est assez mitig\u00e9 et sugg\u00e8re quelques interrogations.<\/p>\n<p>Dans les d\u00e9penses ordinaires, et plus pr\u00e9cis\u00e9ment dans le groupe de \u00ab\u00a0fonctionnement 119 Recettes et D\u00e9penses g\u00e9n\u00e9rales\u00a0\u00bb, nous avons le code de d\u00e9pense \u00ab\u00a0121-04\u00a0: <strong><u>Frais de d\u00e9placements et de s\u00e9jour des mandataires<\/u><\/strong>\u00a0\u00bb. L\u2019article du compte g\u00e9n\u00e9ral est le \u00ab\u00a0<strong><u>61104<\/u><\/strong>\u00a0\u00bb de la comptabilit\u00e9 analytique de toutes les communes. Il faut diff\u00e9rencier ce code des d\u00e9penses par rapport au code voisin \u00ab\u00a0121-01\u00a0: Frais de d\u00e9placements du personnel communal\u00a0\u00bb.<\/p>\n<p>En effet, il s\u2019agit de deux codes diff\u00e9rents, l\u2019un est destin\u00e9 \u00e0 l\u2019usage p\u00e9cuniaire fait par le personnel communal dans tous ses d\u00e9placements professionnels tandis que celui des mandataires doit \u00eatre justifi\u00e9 par des besoins en lien direct avec les fonctions de chaque \u00e9lu et non pas pour prendre du bon temps avec les deniers publics.<\/p>\n<p>Voici un petit tableau\u00a0comparatif non-exhaustif\u00a0:<\/p>\n<table width=\"377\">\n<tbody>\n<tr>\n<td width=\"377\">\n<table width=\"368\">\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"368\"><strong>Budget communal 2016<\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"368\"><strong>Frais de d\u00e9placement et de s\u00e9jour des mandataires<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"148\"><\/td>\n<td width=\"220\"><\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Commune<\/td>\n<td width=\"220\">Montant des d\u00e9penses pour 2016<\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Schaerbeek<\/td>\n<td width=\"220\">10.000 EUR<\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Evere<\/td>\n<td width=\"220\">5.021 EUR<\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Bruxelles-Ville<\/td>\n<td width=\"220\">3.500 EUR<\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Koekelberg<\/td>\n<td width=\"220\">500 EUR<\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Uccle<\/td>\n<td width=\"220\">n\u00e9ant<\/td>\n<\/tr>\n<tr>\n<td width=\"148\"><strong>Saint-Josse-ten-Noode<\/strong><\/td>\n<td width=\"220\"><strong>15.482,90 EUR<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Watermael-Boitsfort<\/td>\n<td width=\"220\">500 EUR<\/td>\n<\/tr>\n<tr>\n<td width=\"148\">Forest<\/td>\n<td width=\"220\">n\u00e9ant<\/td>\n<\/tr>\n<tr>\n<td width=\"148\">\u2026<\/td>\n<td width=\"220\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"377\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Sur le petit \u00e9chantillon r\u00e9sultant de recherches accessibles sur la toile, nous pouvons remarquer que la petite commune de Saint-Josse-ten-Noode est la commune qui a ex\u00e9cut\u00e9 le plus de d\u00e9pense dans cette cat\u00e9gorie.<\/p>\n<p>15.482,90 EUR ont \u00e9t\u00e9 \u00e9coul\u00e9s dans des d\u00e9placements ou voyages nationaux ou internationaux pour l\u2019ann\u00e9e 2016. Ces d\u00e9penses sont fatalement \u00e0 mettre en rapport avec le fait qu\u2019il s\u2019agit bien ici de la commune la plus petite de Bruxelles (avec son petit kilom\u00e8tre carr\u00e9). Pis encore, il ne faut pas omettre qu\u2019il s\u2019agit ici de la commune la plus pauvre de Belgique. M\u00eame Schaerbeek, limitrophe, qui comptabilise au total 13 membres du coll\u00e8ge n\u2019est pas \u00e0 l\u2019hauteur des frais de d\u00e9placement de la commune tennoodoise compos\u00e9e par seulement 8 membres \u00e9lus au coll\u00e8ge.<\/p>\n<p>Enfin, la plus grande commune de Bruxelles qui est Bruxelles-Villes (regroupement 3 communes en son sein) et compos\u00e9e de 11 membres au Coll\u00e8ge n\u2019a fait que 3.500 EUR de d\u00e9pense en s\u00e9jour et d\u00e9placements d\u2019\u00e9lus en 2016.<\/p>\n<p>Erkan Ozdemir \/ La Manchette<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est un fait certain que l\u2019ann\u00e9e 2017 a \u00e9t\u00e9 l\u2019ann\u00e9e butoir de toutes les d\u00e9couvertes ind\u00e9centes des magouilles financi\u00e8res<\/p>\n","protected":false},"author":3,"featured_media":6657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[10,2,8],"tags":[2578,2856],"class_list":["post-6653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-belgique","category-cultures","tag-bourgmestre-woluwe-saint-lambert","tag-frais-de-deplacement-et-de-sejour"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires ! - La Manchette.be<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires ! - La Manchette.be\" \/>\n<meta property=\"og:description\" content=\"Il est un fait certain que l\u2019ann\u00e9e 2017 a \u00e9t\u00e9 l\u2019ann\u00e9e butoir de toutes les d\u00e9couvertes ind\u00e9centes des magouilles financi\u00e8res\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/\" \/>\n<meta property=\"og:site_name\" content=\"La Manchette.be\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lamanchette.be\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100008475673376&amp;ref=bookmarks\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-03T22:56:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-06T11:03:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/11\/4934831267_1ecafc8c1e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"erkan ozdemir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"erkan ozdemir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/\"},\"author\":{\"name\":\"erkan ozdemir\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/person\\\/a7c51ee1e6ff7a2aef02bb01888816a4\"},\"headline\":\"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires !\",\"datePublished\":\"2017-11-03T22:56:50+00:00\",\"dateModified\":\"2017-11-06T11:03:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/\"},\"wordCount\":511,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/4934831267_1ecafc8c1e.jpg\",\"keywords\":[\"bourgmestre Woluw\u00e9-Saint-Lambert\",\"frais de d\u00e9placement et de s\u00e9jour\"],\"articleSection\":[\"Agenda\",\"Belgique\",\"Cultures\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/\",\"name\":\"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires ! - La Manchette.be\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/4934831267_1ecafc8c1e.jpg\",\"datePublished\":\"2017-11-03T22:56:50+00:00\",\"dateModified\":\"2017-11-06T11:03:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/4934831267_1ecafc8c1e.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/4934831267_1ecafc8c1e.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"bourgmestre Woluw\u00e9-Saint-Lambert\",\"item\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/tag\\\/bourgmestre-woluwe-saint-lambert\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#website\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/\",\"name\":\"La Manchette.be\",\"description\":\"L&#039;actualit\u00e9 en belgique sous un angle diff\u00e9rent\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#organization\",\"name\":\"La Manchette\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lamanchette02-e1552859149726.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lamanchette02-e1552859149726.jpg\",\"width\":550,\"height\":190,\"caption\":\"La Manchette\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lamanchette.be\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/person\\\/a7c51ee1e6ff7a2aef02bb01888816a4\",\"name\":\"erkan ozdemir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g\",\"caption\":\"erkan ozdemir\"},\"sameAs\":[\"http:\\\/\\\/www.lamanchette.be\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100008475673376&ref=bookmarks\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires ! - La Manchette.be","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/","og_locale":"fr_FR","og_type":"article","og_title":"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires ! - La Manchette.be","og_description":"Il est un fait certain que l\u2019ann\u00e9e 2017 a \u00e9t\u00e9 l\u2019ann\u00e9e butoir de toutes les d\u00e9couvertes ind\u00e9centes des magouilles financi\u00e8res","og_url":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/","og_site_name":"La Manchette.be","article_publisher":"https:\/\/www.facebook.com\/lamanchette.be\/","article_author":"https:\/\/www.facebook.com\/profile.php?id=100008475673376&ref=bookmarks","article_published_time":"2017-11-03T22:56:50+00:00","article_modified_time":"2017-11-06T11:03:09+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/11\/4934831267_1ecafc8c1e.jpg","type":"image\/jpeg"}],"author":"erkan ozdemir","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"erkan ozdemir","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#article","isPartOf":{"@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/"},"author":{"name":"erkan ozdemir","@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/person\/a7c51ee1e6ff7a2aef02bb01888816a4"},"headline":"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires !","datePublished":"2017-11-03T22:56:50+00:00","dateModified":"2017-11-06T11:03:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/"},"wordCount":511,"commentCount":4,"publisher":{"@id":"https:\/\/www.lamanchette.be\/main\/#organization"},"image":{"@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/11\/4934831267_1ecafc8c1e.jpg","keywords":["bourgmestre Woluw\u00e9-Saint-Lambert","frais de d\u00e9placement et de s\u00e9jour"],"articleSection":["Agenda","Belgique","Cultures"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/","url":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/","name":"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires ! - La Manchette.be","isPartOf":{"@id":"https:\/\/www.lamanchette.be\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#primaryimage"},"image":{"@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/11\/4934831267_1ecafc8c1e.jpg","datePublished":"2017-11-03T22:56:50+00:00","dateModified":"2017-11-06T11:03:09+00:00","breadcrumb":{"@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#primaryimage","url":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/11\/4934831267_1ecafc8c1e.jpg","contentUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/11\/4934831267_1ecafc8c1e.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/www.lamanchette.be\/main\/saint-josse-ten-noode-15-482-eur-en-frais-de-deplacement-et-de-sejour-des-mandataires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lamanchette.be\/main\/"},{"@type":"ListItem","position":2,"name":"bourgmestre Woluw\u00e9-Saint-Lambert","item":"https:\/\/www.lamanchette.be\/main\/tag\/bourgmestre-woluwe-saint-lambert\/"},{"@type":"ListItem","position":3,"name":"Saint-Josse-ten-Noode : 15.482 EUR en frais de d\u00e9placement et de s\u00e9jour des mandataires !"}]},{"@type":"WebSite","@id":"https:\/\/www.lamanchette.be\/main\/#website","url":"https:\/\/www.lamanchette.be\/main\/","name":"La Manchette.be","description":"L&#039;actualit\u00e9 en belgique sous un angle diff\u00e9rent","publisher":{"@id":"https:\/\/www.lamanchette.be\/main\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lamanchette.be\/main\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lamanchette.be\/main\/#organization","name":"La Manchette","url":"https:\/\/www.lamanchette.be\/main\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/logo\/image\/","url":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2019\/01\/lamanchette02-e1552859149726.jpg","contentUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2019\/01\/lamanchette02-e1552859149726.jpg","width":550,"height":190,"caption":"La Manchette"},"image":{"@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lamanchette.be\/"]},{"@type":"Person","@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/person\/a7c51ee1e6ff7a2aef02bb01888816a4","name":"erkan ozdemir","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g","caption":"erkan ozdemir"},"sameAs":["http:\/\/www.lamanchette.be","https:\/\/www.facebook.com\/profile.php?id=100008475673376&ref=bookmarks"]}]}},"_links":{"self":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts\/6653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/comments?post=6653"}],"version-history":[{"count":4,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts\/6653\/revisions"}],"predecessor-version":[{"id":6660,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts\/6653\/revisions\/6660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/media\/6657"}],"wp:attachment":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/media?parent=6653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/categories?post=6653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/tags?post=6653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}