{"id":8527,"date":"2017-12-26T13:21:19","date_gmt":"2017-12-26T12:21:19","guid":{"rendered":"http:\/\/www.lamanchette.be\/main\/?p=8527"},"modified":"2017-12-26T15:43:00","modified_gmt":"2017-12-26T14:43:00","slug":"expulsion-dun-locataire-problematique-comment-faire","status":"publish","type":"post","link":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/","title":{"rendered":"Expulsion d&rsquo;un locataire probl\u00e9matique : comment faire ?"},"content":{"rendered":"<p>A la demande g\u00e9n\u00e9rale, voici les explications sur la proc\u00e9dure l\u00e9gale d&rsquo;expulsion d&rsquo;un locataire probl\u00e9matique.<\/p>\n<p>Il faut savoir que cette proc\u00e9dure n&rsquo;est pas gratuite voire m\u00eame tr\u00e8s ch\u00e8re. Le locataire sera charg\u00e9 de diff\u00e9rents co\u00fbts li\u00e9s \u00e0 la proc\u00e9dure judiciaire. Le propri\u00e9taire aura en contrepartie les frais de repr\u00e9sentation d&rsquo;un avocat en justice de paix.<\/p>\n<p>La tr\u00eave hivernale n&rsquo;est pas une fiction. Il y a une p\u00e9riode pendant laquelle l&rsquo;\u00e9cartement d&rsquo;un locataire est impossible aux yeux de la justice. Evidemment, on parle bien ici d&rsquo;une proc\u00e9dure l\u00e9gale (via la justice) qui est la seule possible.<\/p>\n<p>Bon, on entend souvent qu&rsquo;un propri\u00e9taire veut se faire justice en essayant de faire le n\u00e9cessaire en changeant la serrure ou en appelant les cousins \u00ab\u00a0gros bras\u00a0\u00bb pour ex\u00e9cuter une proc\u00e9dure parall\u00e8le. Ceci constitue donc un acte ill\u00e9gal que le locataire pourrait faire pr\u00e9valoir en justice.<\/p>\n<p>Voici la proc\u00e9dure qui prend enti\u00e8rement sa source sur le site www.lebonbail.be.<\/p>\n<p>L\u2019ex\u00e9cution de la proc\u00e9dure d\u2019expulsion fait suite \u00e0 un non-respect des termes du contrat de bail. L\u2019huissier de justice saisit alors les biens de l\u2019occupant et les d\u00e9place, \u00e0 ses frais, hors du logement. Il existe toutefois des circonstances exceptionnelles pour le locataire, susceptibles de retarder l\u2019expulsion.<\/p>\n<div>\n<div>\n<div>Le propri\u00e9taire ne peut sous aucun pr\u00e9texte expulser le locataire sans recourir \u00e0 la justice. Aussi, l\u2019expulsion ne peut avoir lieu qu\u2019une fois les diff\u00e9rentes \u00e9tapes de la proc\u00e9dure men\u00e9es, la d\u00e9cision du juge rendue et le titre ex\u00e9cutoire obtenu.<\/div>\n<blockquote>\n<div><\/div>\n<div>L\u2019intervention de l\u2019huissier de justice dans l\u2019expulsion du locataire<\/div>\n<\/blockquote>\n<div>Une fois que l\u2019huissier de justice informe le locataire du jugement d\u2019expulsion, ce dernier dispose d\u2019un mois pour quitter les lieux. Le locataire ou le propri\u00e9taire peuvent exceptionnellement demander le prolongement ou la r\u00e9duction de ce d\u00e9lai si des circonstances graves le justifient. L\u2019huissier pr\u00e9vient le locataire par courrier de la date et de l\u2019heure auxquelles l\u2019expulsion est pr\u00e9vue.<\/div>\n<div><\/div>\n<div>Le jour venu:<\/div>\n<ul>\n<li>il se rend au logement avec la police et les agents communaux. S\u2019il ne peut y acc\u00e9der, il peut recourir aux services d\u2019un serrurier.<\/li>\n<li>il dresse alors un proc\u00e8s-verbal \u00e0 la charge du locataire d\u2019un montant d\u2019environ 1200 \u20ac. Si l\u2019acc\u00e8s est tout de m\u00eame bloqu\u00e9, il r\u00e9dige un proc\u00e8s-verbal de tentative d\u2019expulsion et essaie d\u2019entrer avec l\u2019aide des forces publiques.<\/li>\n<\/ul>\n<div>L\u2019acc\u00e8s de force au logement ne peut toutefois se faire sans la pr\u00e9sence du locataire, \u00e0 moins que celui-ci l\u2019ait d\u00e9j\u00e0 quitt\u00e9 d\u00e9finitivement.<\/div>\n<div><\/div>\n<blockquote>\n<div>Les circonstances susceptibles d\u2019emp\u00eacher l\u2019expulsion du locataire<\/div>\n<\/blockquote>\n<div><\/div>\n<div>Horaires d\u2019expulsion et tr\u00eave hivernale<\/div>\n<div>Le locataire ne peut \u00eatre expuls\u00e9 entre 21h et 6h les jours de semaine, ni les dimanches et les jours f\u00e9ri\u00e9s. Il existe \u00e9galement des exceptions concernant les personnes habitant un logement social en r\u00e9gion wallonne ou en r\u00e9gion de Bruxelles-Capitale. Ces personnes ne peuvent \u00eatre expuls\u00e9es :<\/div>\n<ul>\n<li>entre le 1er d\u00e9cembre et le 28 f\u00e9vrier en r\u00e9gion de Bruxelles-Capitale<\/li>\n<\/ul>\n<blockquote><p>Les circonstances exceptionnelles<\/p><\/blockquote>\n<div>Il s\u2019agit de situations d\u2019urgence ou graves qui emp\u00eachent temporairement le locataire de d\u00e9m\u00e9nager ou de chercher un logement, comme par exemple une maladie grave.<\/div>\n<blockquote>\n<div><\/div>\n<div>Que deviennent les meubles en cas d\u2019expulsion du locataire?<\/div>\n<\/blockquote>\n<div><\/div>\n<div>Au cours de la saisie par l\u2019huissier, les biens du locataire sont d\u00e9plac\u00e9s, \u00e0 la charge de ce dernier, \u00e0 l\u2019endroit qu\u2019il indique. Si le locataire n\u2019a pas d\u2019endroit o\u00f9 conserver ses biens, ceux-ci seront stock\u00e9s \u00e0 sa charge \u00e9galement au d\u00e9p\u00f4t communal pendant six mois. S\u2019il refuse ou ne peut pas payer pour les r\u00e9cup\u00e9rer, la commune lui restituera uniquement ses biens insaisissables (lit, v\u00eatements, r\u00e9frig\u00e9rateur, table\u2026). Enfin, lorsque le d\u00e9lai de six mois est d\u00e9pass\u00e9, les meubles sont revendus.<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la demande g\u00e9n\u00e9rale, voici les explications sur la proc\u00e9dure l\u00e9gale d&rsquo;expulsion d&rsquo;un locataire probl\u00e9matique. Il faut savoir que cette<\/p>\n","protected":false},"author":3,"featured_media":8528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[10,2,8],"tags":[2906],"class_list":["post-8527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-belgique","category-cultures","tag-procedure-locataire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expulsion d&#039;un locataire probl\u00e9matique : comment faire ? - La Manchette.be<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expulsion d&#039;un locataire probl\u00e9matique : comment faire ? - La Manchette.be\" \/>\n<meta property=\"og:description\" content=\"A la demande g\u00e9n\u00e9rale, voici les explications sur la proc\u00e9dure l\u00e9gale d&rsquo;expulsion d&rsquo;un locataire probl\u00e9matique. Il faut savoir que cette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/\" \/>\n<meta property=\"og:site_name\" content=\"La Manchette.be\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lamanchette.be\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100008475673376&amp;ref=bookmarks\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-26T12:21:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-26T14:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/12\/logement-expulsion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"erkan ozdemir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"erkan ozdemir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/\"},\"author\":{\"name\":\"erkan ozdemir\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/person\\\/a7c51ee1e6ff7a2aef02bb01888816a4\"},\"headline\":\"Expulsion d&rsquo;un locataire probl\u00e9matique : comment faire ?\",\"datePublished\":\"2017-12-26T12:21:19+00:00\",\"dateModified\":\"2017-12-26T14:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/\"},\"wordCount\":708,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logement-expulsion.jpg\",\"keywords\":[\"proc\u00e9dure locataire\"],\"articleSection\":[\"Agenda\",\"Belgique\",\"Cultures\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/\",\"name\":\"Expulsion d'un locataire probl\u00e9matique : comment faire ? - La Manchette.be\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logement-expulsion.jpg\",\"datePublished\":\"2017-12-26T12:21:19+00:00\",\"dateModified\":\"2017-12-26T14:43:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logement-expulsion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logement-expulsion.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/expulsion-dun-locataire-problematique-comment-faire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"proc\u00e9dure locataire\",\"item\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/tag\\\/procedure-locataire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expulsion d&#8217;un locataire probl\u00e9matique : comment faire ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#website\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/\",\"name\":\"La Manchette.be\",\"description\":\"L&#039;actualit\u00e9 en belgique sous un angle diff\u00e9rent\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#organization\",\"name\":\"La Manchette\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lamanchette02-e1552859149726.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lamanchette02-e1552859149726.jpg\",\"width\":550,\"height\":190,\"caption\":\"La Manchette\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lamanchette.be\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lamanchette.be\\\/main\\\/#\\\/schema\\\/person\\\/a7c51ee1e6ff7a2aef02bb01888816a4\",\"name\":\"erkan ozdemir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g\",\"caption\":\"erkan ozdemir\"},\"sameAs\":[\"http:\\\/\\\/www.lamanchette.be\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100008475673376&ref=bookmarks\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expulsion d'un locataire probl\u00e9matique : comment faire ? - La Manchette.be","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/","og_locale":"fr_FR","og_type":"article","og_title":"Expulsion d'un locataire probl\u00e9matique : comment faire ? - La Manchette.be","og_description":"A la demande g\u00e9n\u00e9rale, voici les explications sur la proc\u00e9dure l\u00e9gale d&rsquo;expulsion d&rsquo;un locataire probl\u00e9matique. Il faut savoir que cette","og_url":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/","og_site_name":"La Manchette.be","article_publisher":"https:\/\/www.facebook.com\/lamanchette.be\/","article_author":"https:\/\/www.facebook.com\/profile.php?id=100008475673376&ref=bookmarks","article_published_time":"2017-12-26T12:21:19+00:00","article_modified_time":"2017-12-26T14:43:00+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/12\/logement-expulsion.jpg","type":"image\/jpeg"}],"author":"erkan ozdemir","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"erkan ozdemir","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#article","isPartOf":{"@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/"},"author":{"name":"erkan ozdemir","@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/person\/a7c51ee1e6ff7a2aef02bb01888816a4"},"headline":"Expulsion d&rsquo;un locataire probl\u00e9matique : comment faire ?","datePublished":"2017-12-26T12:21:19+00:00","dateModified":"2017-12-26T14:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/"},"wordCount":708,"commentCount":0,"publisher":{"@id":"https:\/\/www.lamanchette.be\/main\/#organization"},"image":{"@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/12\/logement-expulsion.jpg","keywords":["proc\u00e9dure locataire"],"articleSection":["Agenda","Belgique","Cultures"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/","url":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/","name":"Expulsion d'un locataire probl\u00e9matique : comment faire ? - La Manchette.be","isPartOf":{"@id":"https:\/\/www.lamanchette.be\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#primaryimage"},"image":{"@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/12\/logement-expulsion.jpg","datePublished":"2017-12-26T12:21:19+00:00","dateModified":"2017-12-26T14:43:00+00:00","breadcrumb":{"@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#primaryimage","url":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/12\/logement-expulsion.jpg","contentUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2017\/12\/logement-expulsion.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.lamanchette.be\/main\/expulsion-dun-locataire-problematique-comment-faire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lamanchette.be\/main\/"},{"@type":"ListItem","position":2,"name":"proc\u00e9dure locataire","item":"https:\/\/www.lamanchette.be\/main\/tag\/procedure-locataire\/"},{"@type":"ListItem","position":3,"name":"Expulsion d&#8217;un locataire probl\u00e9matique : comment faire ?"}]},{"@type":"WebSite","@id":"https:\/\/www.lamanchette.be\/main\/#website","url":"https:\/\/www.lamanchette.be\/main\/","name":"La Manchette.be","description":"L&#039;actualit\u00e9 en belgique sous un angle diff\u00e9rent","publisher":{"@id":"https:\/\/www.lamanchette.be\/main\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lamanchette.be\/main\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lamanchette.be\/main\/#organization","name":"La Manchette","url":"https:\/\/www.lamanchette.be\/main\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/logo\/image\/","url":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2019\/01\/lamanchette02-e1552859149726.jpg","contentUrl":"https:\/\/www.lamanchette.be\/main\/wp-content\/uploads\/2019\/01\/lamanchette02-e1552859149726.jpg","width":550,"height":190,"caption":"La Manchette"},"image":{"@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lamanchette.be\/"]},{"@type":"Person","@id":"https:\/\/www.lamanchette.be\/main\/#\/schema\/person\/a7c51ee1e6ff7a2aef02bb01888816a4","name":"erkan ozdemir","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f26abdd87d028735314b94c4ca45fd8c3f8e97edf30f973dbfcf66cf6daeb14?s=96&d=mm&r=g","caption":"erkan ozdemir"},"sameAs":["http:\/\/www.lamanchette.be","https:\/\/www.facebook.com\/profile.php?id=100008475673376&ref=bookmarks"]}]}},"_links":{"self":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts\/8527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/comments?post=8527"}],"version-history":[{"count":2,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts\/8527\/revisions"}],"predecessor-version":[{"id":8538,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/posts\/8527\/revisions\/8538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/media\/8528"}],"wp:attachment":[{"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/media?parent=8527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/categories?post=8527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamanchette.be\/main\/wp-json\/wp\/v2\/tags?post=8527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}